{"id":4864,"date":"2017-01-18T02:21:59","date_gmt":"2017-01-18T07:21:59","guid":{"rendered":"https:\/\/www.baus.org\/zhtw\/?page_id=4864"},"modified":"2020-11-05T23:56:02","modified_gmt":"2020-11-06T04:56:02","slug":"%e8%8e%8a%e5%9a%b4%e5%af%ba%e6%b4%bb%e5%8b%95","status":"publish","type":"page","link":"https:\/\/www.baus.org\/tc\/%e5%8f%83%e8%a8%aa%e7%be%8e%e4%bd%9b\/%e8%8e%8a%e5%9a%b4%e5%af%ba\/%e8%8e%8a%e5%9a%b4%e5%af%ba%e6%b4%bb%e5%8b%95","title":{"rendered":"\u838a\u56b4\u5bfa\u6d3b\u52d5\u56de\u9867"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4864\" class=\"elementor elementor-4864\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1ed964e2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1ed964e2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5719d03\" data-id=\"5719d03\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-33034bbb elementor-grid-4 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-card-shadow-yes elementor-posts__hover-gradient elementor-widget elementor-widget-posts\" data-id=\"33034bbb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;pagination_type&quot;:&quot;numbers_and_prev_next&quot;,&quot;cards_columns&quot;:&quot;4&quot;,&quot;cards_columns_tablet&quot;:&quot;2&quot;,&quot;cards_columns_mobile&quot;:&quot;1&quot;,&quot;cards_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;cards_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;cards_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.cards\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-cards elementor-grid\" role=\"list\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-12840 post type-post status-publish format-standard has-post-thumbnail hentry category-cym-ceremonies\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.baus.org\/tc\/12840\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" width=\"300\" height=\"300\" src=\"https:\/\/www.baus.org\/tc\/wp-content\/uploads\/2022\/11\/\u5c0f\u5716-300x300.jpg\" class=\"attachment-medium size-medium wp-image-13818\" alt=\"\" srcset=\"https:\/\/www.baus.org\/tc\/wp-content\/uploads\/2022\/11\/\u5c0f\u5716-300x300.jpg 300w, https:\/\/www.baus.org\/tc\/wp-content\/uploads\/2022\/11\/\u5c0f\u5716-150x150.jpg 150w, https:\/\/www.baus.org\/tc\/wp-content\/uploads\/2022\/11\/\u5c0f\u5716.jpg 756w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.baus.org\/tc\/12840\" >\n\t\t\t\t\u5404\u5b97\u6559\u806f\u5408\u7948\u79b1\u6703(\u5df2\u5713\u6eff\u7d50\u675f)\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u6211\u5011\u5f88\u9ad8\u8208\u9080\u8acb\u60a8\u53c3\u52a02024\u5e741\u67081\u65e5\uff08\u661f\u671f\u4e00\uff09\u5143\u65e6\u201c\u4e16\u754c\u548c<\/p>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-13346 post type-post status-publish format-standard has-post-thumbnail hentry category-cym-ceremonies\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.baus.org\/tc\/13346\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" width=\"300\" height=\"300\" src=\"https:\/\/www.baus.org\/tc\/wp-content\/uploads\/2022\/05\/\u89c0\u97f3\u6210\u9053-300x300.jpg\" class=\"attachment-medium size-medium wp-image-12557\" alt=\"\" srcset=\"https:\/\/www.baus.org\/tc\/wp-content\/uploads\/2022\/05\/\u89c0\u97f3\u6210\u9053-300x300.jpg 300w, https:\/\/www.baus.org\/tc\/wp-content\/uploads\/2022\/05\/\u89c0\u97f3\u6210\u9053-150x150.jpg 150w, https:\/\/www.baus.org\/tc\/wp-content\/uploads\/2022\/05\/\u89c0\u97f3\u6210\u9053.jpg 720w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.baus.org\/tc\/13346\" >\n\t\t\t\t\u89c0\u97f3\u6210\u9053\u7d00\u5ff5\u6cd5\u6703(\u5df2\u5713\u6eff\u7d50\u675f)\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u672c\u5bfa\u8b39\u8a02\u65bc2025\u5e747\u670813\u65e510:00am ~ 12:15<\/p>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-15022 post type-post status-publish format-standard has-post-thumbnail hentry category-cym-ceremonies\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.baus.org\/tc\/15022\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" width=\"300\" height=\"116\" src=\"https:\/\/www.baus.org\/tc\/wp-content\/uploads\/2023\/05\/609e05ca-1b61-4eb4-a35c-80757954d6db-300x116.jpg\" class=\"attachment-medium size-medium wp-image-13245\" alt=\"\" srcset=\"https:\/\/www.baus.org\/tc\/wp-content\/uploads\/2023\/05\/609e05ca-1b61-4eb4-a35c-80757954d6db-300x116.jpg 300w, https:\/\/www.baus.org\/tc\/wp-content\/uploads\/2023\/05\/609e05ca-1b61-4eb4-a35c-80757954d6db.jpg 700w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.baus.org\/tc\/15022\" >\n\t\t\t\t\u838a\u56b4\u884c\u8005\u4e4b\u8def (\u5df2\u5713\u6eff\u7d50\u675f)\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u7dda\u4e0a\u5831\u540d \u6388\u8ab2\u5e2b\u9577 \u2191\u6709\u668b\u6cd5\u5e2b\u2191 \u2191\u6709\u6662\u6cd5\u5e2b\u2191 \u4e3b\u984c\uff1a\u884c\u8005\u4e4b<\/p>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-15071 post type-post status-publish format-standard has-post-thumbnail hentry category-wjml-programs category-baus-activities category-cym-activities\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.baus.org\/tc\/15071\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" width=\"225\" height=\"300\" src=\"https:\/\/www.baus.org\/tc\/wp-content\/uploads\/2025\/07\/image02-225x300.jpeg\" class=\"attachment-medium size-medium wp-image-15070\" alt=\"\" srcset=\"https:\/\/www.baus.org\/tc\/wp-content\/uploads\/2025\/07\/image02-225x300.jpeg 225w, https:\/\/www.baus.org\/tc\/wp-content\/uploads\/2025\/07\/image02-768x1024.jpeg 768w, https:\/\/www.baus.org\/tc\/wp-content\/uploads\/2025\/07\/image02.jpeg 1080w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.baus.org\/tc\/15071\" >\n\t\t\t\t\u4f5b\u6cd5\u5ea7\u8ac7(\u5df2\u5713\u6eff\u7d50\u675f)\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u5730\u9ede\uff1a\u548c\u5982\u7d00\u5ff5\u5716\u66f8\u9928 \u65e5\u671f\uff1a8\u670824\u65e52025\u5e74\uff08\u661f\u671f\u65e5\uff09 <\/p>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-14777 post type-post status-publish format-standard has-post-thumbnail hentry category-cym-ceremonies\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.baus.org\/tc\/14777\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" width=\"300\" height=\"168\" src=\"https:\/\/www.baus.org\/tc\/wp-content\/uploads\/2025\/02\/images1.jpg\" class=\"attachment-medium size-medium wp-image-14778\" alt=\"\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.baus.org\/tc\/14777\" >\n\t\t\t\t\u745c\u73c8\u83e9\u85a9\u6212\u7814\u7fd2\u71df(\u5df2\u5713\u6eff\u7d50\u675f)\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>1992\u5e74\u5728\u57d4\u91cc\u6b63\u89ba\u7cbe\u820d\u65bc\u4e0a\u9053\u4e0b\u6d77\u5f8b\u5e2b\u5ea7\u4e0b\u51fa\u5bb6\uff0c1993\u5e743<\/p>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-14516 post type-post status-publish format-standard has-post-thumbnail hentry category-cym-ceremonies\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.baus.org\/tc\/14516\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" width=\"206\" height=\"300\" src=\"https:\/\/www.baus.org\/tc\/wp-content\/uploads\/2024\/10\/Bhaisajyaguru-1-206x300.jpg\" class=\"attachment-medium size-medium wp-image-14521\" alt=\"\" srcset=\"https:\/\/www.baus.org\/tc\/wp-content\/uploads\/2024\/10\/Bhaisajyaguru-1-206x300.jpg 206w, https:\/\/www.baus.org\/tc\/wp-content\/uploads\/2024\/10\/Bhaisajyaguru-1-704x1024.jpg 704w, https:\/\/www.baus.org\/tc\/wp-content\/uploads\/2024\/10\/Bhaisajyaguru-1-768x1117.jpg 768w, https:\/\/www.baus.org\/tc\/wp-content\/uploads\/2024\/10\/Bhaisajyaguru-1-1056x1536.jpg 1056w, https:\/\/www.baus.org\/tc\/wp-content\/uploads\/2024\/10\/Bhaisajyaguru-1.jpg 1170w\" sizes=\"auto, (max-width: 206px) 100vw, 206px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.baus.org\/tc\/14516\" >\n\t\t\t\t\u85e5\u5e2b\u6cd5\u6703(\u5df2\u5713\u6eff\u7d50\u675f)\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u6d88\u707d\u5ef6\u58fd\u85e5\u5e2b\u4f5b_\u6cd5\u6703\u5171\u4fee \u7dda\u4e0a\u9ede\u71c8 \u4f4f\u5bbf\u767b\u8a18 \u2191\u6cd5\u6703\u4f5c\u7fd2\u6642\u9593<\/p>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-14109 post type-post status-publish format-standard has-post-thumbnail hentry category-cym-ceremonies\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.baus.org\/tc\/14109\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" width=\"200\" height=\"300\" src=\"https:\/\/www.baus.org\/tc\/wp-content\/uploads\/2024\/04\/Yellow-And-Red-Playful-Family-Fun-Day-Flyer-Smooth-Plastic-Sign-12-x-18-in-2-200x300.png\" class=\"attachment-medium size-medium wp-image-14160\" alt=\"\" srcset=\"https:\/\/www.baus.org\/tc\/wp-content\/uploads\/2024\/04\/Yellow-And-Red-Playful-Family-Fun-Day-Flyer-Smooth-Plastic-Sign-12-x-18-in-2-200x300.png 200w, https:\/\/www.baus.org\/tc\/wp-content\/uploads\/2024\/04\/Yellow-And-Red-Playful-Family-Fun-Day-Flyer-Smooth-Plastic-Sign-12-x-18-in-2-682x1024.png 682w, https:\/\/www.baus.org\/tc\/wp-content\/uploads\/2024\/04\/Yellow-And-Red-Playful-Family-Fun-Day-Flyer-Smooth-Plastic-Sign-12-x-18-in-2-768x1152.png 768w, https:\/\/www.baus.org\/tc\/wp-content\/uploads\/2024\/04\/Yellow-And-Red-Playful-Family-Fun-Day-Flyer-Smooth-Plastic-Sign-12-x-18-in-2-1024x1536.png 1024w, https:\/\/www.baus.org\/tc\/wp-content\/uploads\/2024\/04\/Yellow-And-Red-Playful-Family-Fun-Day-Flyer-Smooth-Plastic-Sign-12-x-18-in-2.png 1333w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.baus.org\/tc\/14109\" >\n\t\t\t\t\u91d1\u525b\u7d93\u7814\u7fd2\u71df\uff088\u30019\u300110\u6708\u4efd\uff09\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u6176\u795d\u7f8e\u570b\u4f5b\u6559\u6703\u6210\u7acb\u516d\u5341\u5468\u5e74\uff0c\u66a8\u6c88\u5bb6\u6968\u5c45\u58eb\u3001\u5c45\u548c\u5982\u5c45\u58eb\u7d00\u5ff5\u9928\u6210<\/p>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-14395 post type-post status-publish format-standard has-post-thumbnail hentry category-cym-ceremonies\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.baus.org\/tc\/14395\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" width=\"300\" height=\"300\" src=\"https:\/\/www.baus.org\/tc\/wp-content\/uploads\/2024\/07\/\u5c0f\u5716-300x300.jpg\" class=\"attachment-medium size-medium wp-image-14413\" alt=\"\" srcset=\"https:\/\/www.baus.org\/tc\/wp-content\/uploads\/2024\/07\/\u5c0f\u5716-300x300.jpg 300w, https:\/\/www.baus.org\/tc\/wp-content\/uploads\/2024\/07\/\u5c0f\u5716-150x150.jpg 150w, https:\/\/www.baus.org\/tc\/wp-content\/uploads\/2024\/07\/\u5c0f\u5716.jpg 720w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.baus.org\/tc\/14395\" >\n\t\t\t\t\u6881\u7687\u5bf6\u61fa\u5927\u6cd5\u6703(\u5df2\u5713\u6eff\u7d50\u675f)\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u7dda\u4e0a\u586b\u5beb\u724c\u4f4d \u529f\u5fb7\u4e3b_\u4f9b\u9f4b_\u767b\u8a18\u8868_\u4e0b\u8f09 \u6d88\u707d\u8d85\u5ea6_\u767b\u8a18\u8868_<\/p>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-14118 post type-post status-publish format-standard has-post-thumbnail hentry category-cym-ceremonies\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.baus.org\/tc\/14118\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" width=\"300\" height=\"214\" src=\"https:\/\/www.baus.org\/tc\/wp-content\/uploads\/2024\/04\/Youre-Invite-to-Grand-Opening-of-Mr.-C.-T-Shen-Memorial-Room-at-Woo-Ju-Memorial-Library-BAUS-300x214.png\" class=\"attachment-medium size-medium wp-image-14133\" alt=\"\" srcset=\"https:\/\/www.baus.org\/tc\/wp-content\/uploads\/2024\/04\/Youre-Invite-to-Grand-Opening-of-Mr.-C.-T-Shen-Memorial-Room-at-Woo-Ju-Memorial-Library-BAUS-300x214.png 300w, https:\/\/www.baus.org\/tc\/wp-content\/uploads\/2024\/04\/Youre-Invite-to-Grand-Opening-of-Mr.-C.-T-Shen-Memorial-Room-at-Woo-Ju-Memorial-Library-BAUS-1024x731.png 1024w, https:\/\/www.baus.org\/tc\/wp-content\/uploads\/2024\/04\/Youre-Invite-to-Grand-Opening-of-Mr.-C.-T-Shen-Memorial-Room-at-Woo-Ju-Memorial-Library-BAUS-768x548.png 768w, https:\/\/www.baus.org\/tc\/wp-content\/uploads\/2024\/04\/Youre-Invite-to-Grand-Opening-of-Mr.-C.-T-Shen-Memorial-Room-at-Woo-Ju-Memorial-Library-BAUS-1536x1097.png 1536w, https:\/\/www.baus.org\/tc\/wp-content\/uploads\/2024\/04\/Youre-Invite-to-Grand-Opening-of-Mr.-C.-T-Shen-Memorial-Room-at-Woo-Ju-Memorial-Library-BAUS.png 2000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.baus.org\/tc\/14118\" >\n\t\t\t\t\u6c88\u5bb6\u6968_\u7d00\u5ff5\u5ba4\u555f\u7528\uff08\u5df2\u5713\u6eff\u7d50\u675f\uff09\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u52e4\u4fee\u798f\u6167\uff0c\u7a7a\u76f8\u4f48\u65bd \u6c88\u5bb6\u6968\u5c45\u58eb (1913-2007), \u7f8e<\/p>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-14424 post type-post status-publish format-standard has-post-thumbnail hentry category-cym-ceremonies\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.baus.org\/tc\/14424\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" width=\"300\" height=\"300\" src=\"https:\/\/www.baus.org\/tc\/wp-content\/uploads\/2021\/09\/\u51fa\u5bb6\u6cd5\u6703-300x300.jpg\" class=\"attachment-medium size-medium wp-image-11948\" alt=\"\" srcset=\"https:\/\/www.baus.org\/tc\/wp-content\/uploads\/2021\/09\/\u51fa\u5bb6\u6cd5\u6703-300x300.jpg 300w, https:\/\/www.baus.org\/tc\/wp-content\/uploads\/2021\/09\/\u51fa\u5bb6\u6cd5\u6703-150x150.jpg 150w, https:\/\/www.baus.org\/tc\/wp-content\/uploads\/2021\/09\/\u51fa\u5bb6\u6cd5\u6703-768x768.jpg 768w, https:\/\/www.baus.org\/tc\/wp-content\/uploads\/2021\/09\/\u51fa\u5bb6\u6cd5\u6703.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.baus.org\/tc\/14424\" >\n\t\t\t\t\u89c0\u97f3\u51fa\u5bb6\u7d00\u5ff5\u6cd5\u6703\uff08\u5df2\u5713\u6eff\u7d50\u675f\uff09\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u7dda\u4e0a\u9ede\u71c8\u7948\u798f \u672c\u5bfa\u8b39\u8a02\u65bc2024\u5e7410\u670820\u65e510:00am<\/p>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-14489 post type-post status-publish format-standard has-post-thumbnail hentry category-cym-ceremonies\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.baus.org\/tc\/14489\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" width=\"232\" height=\"300\" src=\"https:\/\/www.baus.org\/tc\/wp-content\/uploads\/2024\/10\/Copy-of-BAUS-1-232x300.png\" class=\"attachment-medium size-medium wp-image-14508\" alt=\"\" srcset=\"https:\/\/www.baus.org\/tc\/wp-content\/uploads\/2024\/10\/Copy-of-BAUS-1-232x300.png 232w, https:\/\/www.baus.org\/tc\/wp-content\/uploads\/2024\/10\/Copy-of-BAUS-1-791x1024.png 791w, https:\/\/www.baus.org\/tc\/wp-content\/uploads\/2024\/10\/Copy-of-BAUS-1-768x994.png 768w, https:\/\/www.baus.org\/tc\/wp-content\/uploads\/2024\/10\/Copy-of-BAUS-1-1187x1536.png 1187w, https:\/\/www.baus.org\/tc\/wp-content\/uploads\/2024\/10\/Copy-of-BAUS-1.png 1545w\" sizes=\"auto, (max-width: 232px) 100vw, 232px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.baus.org\/tc\/14489\" >\n\t\t\t\t\u4ee5\u5370\u9806\u5c0e\u5e2b\u79d1\u5224\u89e3\u8b80\u5fc3\u7d93\u3001\u91d1\u525b\u7d93\u5927\u610f(\u5df2\u5713\u6eff\u7d50\u675f)\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u9ede\u64ca\u9019\u88e1\u5831\u540d<\/p>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-13748 post type-post status-publish format-standard has-post-thumbnail hentry category-cym-ceremonies\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.baus.org\/tc\/13748\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" width=\"300\" height=\"300\" src=\"https:\/\/www.baus.org\/tc\/wp-content\/uploads\/2023\/09\/\u50b3\u6212\u5c0f\u5716J-300x300.jpg\" class=\"attachment-medium size-medium wp-image-13765\" alt=\"\" srcset=\"https:\/\/www.baus.org\/tc\/wp-content\/uploads\/2023\/09\/\u50b3\u6212\u5c0f\u5716J-300x300.jpg 300w, https:\/\/www.baus.org\/tc\/wp-content\/uploads\/2023\/09\/\u50b3\u6212\u5c0f\u5716J-150x150.jpg 150w, https:\/\/www.baus.org\/tc\/wp-content\/uploads\/2023\/09\/\u50b3\u6212\u5c0f\u5716J.jpg 756w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.baus.org\/tc\/13748\" >\n\t\t\t\t2024\u50b3\u6388\u4e94\u6212\u83e9\u85a9\u6212\uff08\u5df2\u5713\u6eff\u7d50\u675f\uff09\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>https:\/\/youtu.be\/tswsww3gG3Yht<\/p>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t<div class=\"e-load-more-anchor\" data-page=\"1\" data-max-page=\"22\" data-next-page=\"https:\/\/www.baus.org\/tc\/wp-json\/wp\/v2\/pages\/4864\/page\/2\"><\/div>\n\t\t\t\t<nav class=\"elementor-pagination\" aria-label=\"\u5206\u9801\">\n\t\t\t<span class=\"page-numbers prev\">&laquo; \u4e0a\u4e00\u9801<\/span>\n<span aria-current=\"page\" class=\"page-numbers current\"><span class=\"elementor-screen-only\">\u9801\u9762<\/span>1<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/www.baus.org\/tc\/wp-json\/wp\/v2\/pages\/4864\/page\/2\"><span class=\"elementor-screen-only\">\u9801\u9762<\/span>2<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/www.baus.org\/tc\/wp-json\/wp\/v2\/pages\/4864\/page\/3\"><span class=\"elementor-screen-only\">\u9801\u9762<\/span>3<\/a>\n<span class=\"page-numbers dots\">...<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/www.baus.org\/tc\/wp-json\/wp\/v2\/pages\/4864\/page\/22\"><span class=\"elementor-screen-only\">\u9801\u9762<\/span>22<\/a>\n<a class=\"page-numbers next\" href=\"https:\/\/www.baus.org\/tc\/wp-json\/wp\/v2\/pages\/4864\/page\/2\">\u4e0b\u4e00\u9801 &raquo;<\/a>\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":4744,"menu_order":180,"comment_status":"closed","ping_status":"closed","template":"tpl-visit-group-home.php","meta":{"_acf_changed":false,"nf_dc_page":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":"","_members_access_role":[],"_members_access_error":""},"class_list":["post-4864","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u838a\u56b4\u5bfa\u6d3b\u52d5\u56de\u9867 -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.baus.org\/tc\/\u53c3\u8a2a\u7f8e\u4f5b\/\u838a\u56b4\u5bfa\/\u838a\u56b4\u5bfa\u6d3b\u52d5\" \/>\n<meta property=\"og:locale\" content=\"zh_TW\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u838a\u56b4\u5bfa\u6d3b\u52d5\u56de\u9867 -\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.baus.org\/tc\/\u53c3\u8a2a\u7f8e\u4f5b\/\u838a\u56b4\u5bfa\/\u838a\u56b4\u5bfa\u6d3b\u52d5\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-06T04:56:02+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.baus.org\\\/tc\\\/%e5%8f%83%e8%a8%aa%e7%be%8e%e4%bd%9b\\\/%e8%8e%8a%e5%9a%b4%e5%af%ba\\\/%e8%8e%8a%e5%9a%b4%e5%af%ba%e6%b4%bb%e5%8b%95\",\"url\":\"https:\\\/\\\/www.baus.org\\\/tc\\\/%e5%8f%83%e8%a8%aa%e7%be%8e%e4%bd%9b\\\/%e8%8e%8a%e5%9a%b4%e5%af%ba\\\/%e8%8e%8a%e5%9a%b4%e5%af%ba%e6%b4%bb%e5%8b%95\",\"name\":\"\u838a\u56b4\u5bfa\u6d3b\u52d5\u56de\u9867 -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.baus.org\\\/tc\\\/#website\"},\"datePublished\":\"2017-01-18T07:21:59+00:00\",\"dateModified\":\"2020-11-06T04:56:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.baus.org\\\/tc\\\/%e5%8f%83%e8%a8%aa%e7%be%8e%e4%bd%9b\\\/%e8%8e%8a%e5%9a%b4%e5%af%ba\\\/%e8%8e%8a%e5%9a%b4%e5%af%ba%e6%b4%bb%e5%8b%95#breadcrumb\"},\"inLanguage\":\"zh-TW\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.baus.org\\\/tc\\\/%e5%8f%83%e8%a8%aa%e7%be%8e%e4%bd%9b\\\/%e8%8e%8a%e5%9a%b4%e5%af%ba\\\/%e8%8e%8a%e5%9a%b4%e5%af%ba%e6%b4%bb%e5%8b%95\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.baus.org\\\/tc\\\/%e5%8f%83%e8%a8%aa%e7%be%8e%e4%bd%9b\\\/%e8%8e%8a%e5%9a%b4%e5%af%ba\\\/%e8%8e%8a%e5%9a%b4%e5%af%ba%e6%b4%bb%e5%8b%95#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u9996\u9801\",\"item\":\"https:\\\/\\\/www.baus.org\\\/tc\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u53c3\u8a2a\u7f8e\u4f5b\",\"item\":\"https:\\\/\\\/www.baus.org\\\/tc\\\/%e5%8f%83%e8%a8%aa%e7%be%8e%e4%bd%9b\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u838a\u56b4\u5bfa\",\"item\":\"https:\\\/\\\/www.baus.org\\\/tc\\\/%e5%8f%83%e8%a8%aa%e7%be%8e%e4%bd%9b\\\/%e8%8e%8a%e5%9a%b4%e5%af%ba\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"\u838a\u56b4\u5bfa\u6d3b\u52d5\u56de\u9867\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.baus.org\\\/tc\\\/#website\",\"url\":\"https:\\\/\\\/www.baus.org\\\/tc\\\/\",\"name\":\"\",\"description\":\"\u767c\u83e9\u63d0\u5fc3\uff0c\u958b\u555f\u667a\u6167\u4e4b\u9580\u7684\u5730\u65b9\uff01\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.baus.org\\\/tc\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-TW\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u838a\u56b4\u5bfa\u6d3b\u52d5\u56de\u9867 -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.baus.org\/tc\/\u53c3\u8a2a\u7f8e\u4f5b\/\u838a\u56b4\u5bfa\/\u838a\u56b4\u5bfa\u6d3b\u52d5","og_locale":"zh_TW","og_type":"article","og_title":"\u838a\u56b4\u5bfa\u6d3b\u52d5\u56de\u9867 -","og_url":"https:\/\/www.baus.org\/tc\/\u53c3\u8a2a\u7f8e\u4f5b\/\u838a\u56b4\u5bfa\/\u838a\u56b4\u5bfa\u6d3b\u52d5","article_modified_time":"2020-11-06T04:56:02+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.baus.org\/tc\/%e5%8f%83%e8%a8%aa%e7%be%8e%e4%bd%9b\/%e8%8e%8a%e5%9a%b4%e5%af%ba\/%e8%8e%8a%e5%9a%b4%e5%af%ba%e6%b4%bb%e5%8b%95","url":"https:\/\/www.baus.org\/tc\/%e5%8f%83%e8%a8%aa%e7%be%8e%e4%bd%9b\/%e8%8e%8a%e5%9a%b4%e5%af%ba\/%e8%8e%8a%e5%9a%b4%e5%af%ba%e6%b4%bb%e5%8b%95","name":"\u838a\u56b4\u5bfa\u6d3b\u52d5\u56de\u9867 -","isPartOf":{"@id":"https:\/\/www.baus.org\/tc\/#website"},"datePublished":"2017-01-18T07:21:59+00:00","dateModified":"2020-11-06T04:56:02+00:00","breadcrumb":{"@id":"https:\/\/www.baus.org\/tc\/%e5%8f%83%e8%a8%aa%e7%be%8e%e4%bd%9b\/%e8%8e%8a%e5%9a%b4%e5%af%ba\/%e8%8e%8a%e5%9a%b4%e5%af%ba%e6%b4%bb%e5%8b%95#breadcrumb"},"inLanguage":"zh-TW","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.baus.org\/tc\/%e5%8f%83%e8%a8%aa%e7%be%8e%e4%bd%9b\/%e8%8e%8a%e5%9a%b4%e5%af%ba\/%e8%8e%8a%e5%9a%b4%e5%af%ba%e6%b4%bb%e5%8b%95"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.baus.org\/tc\/%e5%8f%83%e8%a8%aa%e7%be%8e%e4%bd%9b\/%e8%8e%8a%e5%9a%b4%e5%af%ba\/%e8%8e%8a%e5%9a%b4%e5%af%ba%e6%b4%bb%e5%8b%95#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u9996\u9801","item":"https:\/\/www.baus.org\/tc\/"},{"@type":"ListItem","position":2,"name":"\u53c3\u8a2a\u7f8e\u4f5b","item":"https:\/\/www.baus.org\/tc\/%e5%8f%83%e8%a8%aa%e7%be%8e%e4%bd%9b"},{"@type":"ListItem","position":3,"name":"\u838a\u56b4\u5bfa","item":"https:\/\/www.baus.org\/tc\/%e5%8f%83%e8%a8%aa%e7%be%8e%e4%bd%9b\/%e8%8e%8a%e5%9a%b4%e5%af%ba"},{"@type":"ListItem","position":4,"name":"\u838a\u56b4\u5bfa\u6d3b\u52d5\u56de\u9867"}]},{"@type":"WebSite","@id":"https:\/\/www.baus.org\/tc\/#website","url":"https:\/\/www.baus.org\/tc\/","name":"","description":"\u767c\u83e9\u63d0\u5fc3\uff0c\u958b\u555f\u667a\u6167\u4e4b\u9580\u7684\u5730\u65b9\uff01","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.baus.org\/tc\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-TW"}]}},"_links":{"self":[{"href":"https:\/\/www.baus.org\/tc\/wp-json\/wp\/v2\/pages\/4864","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.baus.org\/tc\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.baus.org\/tc\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.baus.org\/tc\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.baus.org\/tc\/wp-json\/wp\/v2\/comments?post=4864"}],"version-history":[{"count":7,"href":"https:\/\/www.baus.org\/tc\/wp-json\/wp\/v2\/pages\/4864\/revisions"}],"predecessor-version":[{"id":10166,"href":"https:\/\/www.baus.org\/tc\/wp-json\/wp\/v2\/pages\/4864\/revisions\/10166"}],"up":[{"embeddable":true,"href":"https:\/\/www.baus.org\/tc\/wp-json\/wp\/v2\/pages\/4744"}],"wp:attachment":[{"href":"https:\/\/www.baus.org\/tc\/wp-json\/wp\/v2\/media?parent=4864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}